{"id":18093,"date":"2020-04-09T09:53:08","date_gmt":"2020-04-09T09:53:08","guid":{"rendered":"https:\/\/adra.org\/?p=18093"},"modified":"2026-03-31T15:41:45","modified_gmt":"2026-03-31T15:41:45","slug":"news-release-adras-good-goes-viral-campaign-encourages-doing-good-deeds","status":"publish","type":"post","link":"https:\/\/adra.org\/fr\/news-release-adras-good-goes-viral-campaign-encourages-doing-good-deeds","title":{"rendered":"Communiqu\u00e9 de presse : La campagne \u201cGood Goes Viral\u201d de l'ADRA encourage les bonnes actions"},"content":{"rendered":"<h2 class=\"wp-block-heading\">\u201cLe bien devient viral\u201d : Faire le bien et partager l'amour pendant la crise du COVID-19<\/h2>\n\n\n\n<figure><img decoding=\"async\" src=\"https:\/\/adra.org\/wp-content\/uploads\/2020\/04\/20-050.01_GGV_Web_Banner-1-1024x256.png\" alt=\"\"\/><\/figure>\n\n\n\n<p><strong>Silver Spring, MD (9 avril 2020)<\/strong> -L'Agence adventiste de d\u00e9veloppement et d'assistance (ADRA) lance le programme&nbsp;<strong>Good Goes Viral (#GoodGoesViral) <\/strong>un mouvement visant \u00e0 inciter le monde \u00e0 s'engager dans des actes de bont\u00e9 \u00e0 partir du week-end de P\u00e2ques, \u00e0 prier pour les personnes touch\u00e9es par la crise du COVID-19 et \u00e0 soutenir la r\u00e9ponse globale de l'ADRA \u00e0 la pand\u00e9mie.<\/p>\n\n\n\n<p>\u00c0 l'heure o\u00f9 des millions de personnes restent \u00e0 la maison, la\n\u00e0 une \u00e9poque o\u00f9 des millions de personnes restent \u00e0 la maison, les <strong>Le bien devient viral <\/strong>encourage les gens \u00e0 faire le bien en partageant l'amour et la gentillesse\nen partageant l'amour et la gentillesse de mani\u00e8re cr\u00e9ative afin de cr\u00e9er un lien entre la famille, les amis, les voisins et les \u00e9trangers, tout en maintenant la coh\u00e9sion sociale.\nentre la famille, les amis, les voisins et les \u00e9trangers, tout en maintenant une\ndistance sociale. <\/p>\n\n\n\n<p>\u201cC'est un moment o\u00f9 nous devons \u00eatre l\u00e0 les uns pour les autres, surtout pour les personnes les plus vuln\u00e9rables.\nC'est une p\u00e9riode o\u00f9 nous devons \u00eatre l\u00e0 les uns pour les autres, en particulier pour les plus vuln\u00e9rables d'entre nous.\nles plus vuln\u00e9rables d'entre nous. Plus que jamais, nous avons la responsabilit\u00e9 et le privil\u00e8ge de prendre soin les uns des autres et de servir comme J\u00e9sus nous l'a ordonn\u00e9\u201d.\nprivil\u00e8ge de prendre soin les uns des autres et de servir comme J\u00e9sus nous l'a ordonn\u00e9\", d\u00e9clare Mario Oliveira, directeur de l'\u00e9quipe de gestion des urgences d'ADRA.\nMario Oliveira, directeur de l'\u00e9quipe de gestion des urgences d'ADRA.<\/p>\n\n\n\n<p>Dans le cadre de cet effort, ADRA appelle \u00e9galement les gens \u00e0 prier.\nDans le cadre de cet effort, ADRA appelle \u00e9galement les gens \u00e0 prier, surtout en cette p\u00e9riode de P\u00e2ques.\nde P\u00e2ques. \u00c0 cette fin, ADRA\na ouvert des lignes de pri\u00e8re tous les lundis \u00e0 midi (EDT) \u00e0 l'adresse suivante <a href=\"https:\/\/adra.org\/fr\/coronavirus\/\" target=\"_blank\" rel=\"noreferrer noopener\">ADRA.org\/coronavirus<\/a> de prier en ligne pour ceux qui souffrent du coronavirus\npour ceux qui souffrent de la pand\u00e9mie de coronavirus (COVID-19).\npand\u00e9mie. En outre, <strong>Le bien devient viral<\/strong> offre aux personnes\n\u00e0 distance des possibilit\u00e9s de soutenir des op\u00e9rations de secours pour les personnes COVID-19 touch\u00e9es\ndans le monde entier et encourage les communaut\u00e9s \u00e0 cr\u00e9er des activit\u00e9s pour rester en s\u00e9curit\u00e9 et en bonne sant\u00e9 pendant la p\u00e9riode o\u00f9 elles restent \u00e0 la maison afin d'emp\u00eacher la propagation du virus.\net en bonne sant\u00e9 pendant la p\u00e9riode de s\u00e9jour \u00e0 domicile afin d'enrayer la propagation du coronavirus.\ncoronavirus. <\/p>\n\n\n\n<p>ADRA dessert plus de 2,4 millions de m\u00e9nages\ndans le monde o\u00f9 la vie a \u00e9t\u00e9 boulevers\u00e9e par la pand\u00e9mie de\npendant la pand\u00e9mie de coronavirus. Des plans sont \u00e9galement en place pour aider les communaut\u00e9s\n\u00e0 long terme pendant la phase de r\u00e9tablissement. Les efforts d'aide d'ADRA\nsoutiennent les communaut\u00e9s vuln\u00e9rables et mal desservies, en particulier les\nles personnes \u00e2g\u00e9es, les personnes licenci\u00e9es et bien d'autres encore, afin de s'assurer qu'elles re\u00e7oivent l'aide dont elles ont besoin.\nqu'elles re\u00e7oivent l'aide n\u00e9cessaire.&nbsp;<\/p>\n\n\n\n<p>\u201cCe que nous voyons est d'une ampleur sans pr\u00e9c\u00e9dent. Au cours des derni\u00e8res semaines, ADRA a d\u00e9ploy\u00e9 des \u00e9quipes dans plus de 70 pays pour r\u00e9pondre aux besoins imm\u00e9diats des personnes et des familles touch\u00e9es par la pand\u00e9mie et par la r\u00e9cession \u00e9conomique qui en a r\u00e9sult\u00e9\u201d, d\u00e9clare M. Oliveira. \u201cAlors que nos travailleurs et b\u00e9n\u00e9voles d\u00e9vou\u00e9s sont en premi\u00e8re ligne de la r\u00e9ponse au coronavirus et fournissent une gamme d'assistance - distribution de masques, de kits alimentaires, de bons d'achat, de d\u00e9sinfectants pour les mains et sensibilisation \u00e0 l'hygi\u00e8ne - nous avons besoin d'un soutien accru pour garantir qu'ADRA puisse continuer \u00e0 fournir l'aide vitale \u00e0 ceux qui luttent le plus. Jamais le besoin n'a \u00e9t\u00e9 aussi grand et jamais notre travail n'a \u00e9t\u00e9 aussi n\u00e9cessaire qu'aujourd'hui\u201d.\u201d&nbsp;<\/p>\n\n\n\n<p>Ce week-end de P\u00e2ques, ADRA invite les personnes de tous horizons et de toutes communaut\u00e9s \u00e0 se joindre \u00e0 elle. <strong>Le bien devient viral<\/strong> en s'engageant dans des activit\u00e9s positives qui encouragent les autres et apportent de l'espoir \u00e0 ceux qui en ont le plus besoin. Les personnes peuvent rejoindre le mouvement en s'engageant dans l'une des activit\u00e9s suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Faites un don aux efforts d'ADRA en faveur de la lutte contre le COVID-19 dans le monde entier (pour en savoir plus, consultez le site suivant <a rel=\"noreferrer noopener\" href=\"https:\/\/donations.adra.org\/covidresponse-ws\" target=\"_blank\">ADRA.org\/covidresponse<\/a>) &nbsp;&nbsp;&nbsp;&nbsp;<\/li><li>Organiser un d\u00e9jeuner ou un d\u00eener hebdomadaire virtuel avec des amis ou des membres de la famille<\/li><li>Rejoignez la discussion en direct d'ADRA sur Facebook sur l'espoir et la pri\u00e8re tous les lundis \u00e0 12 heures (EDT). (Les demandes de pri\u00e8re peuvent \u00eatre soumises \u00e0 <a rel=\"noreferrer noopener\" href=\"https:\/\/adra.org\/fr\/coronavirus\/\" target=\"_blank\">ADRA.org\/coronavirus<\/a>.)<\/li><li>Prier pour les voisins, les parents, les amis et les personnes touch\u00e9es par la pand\u00e9mie.<\/li><li>Partager des pens\u00e9es inspirantes ou des versets bibliques avec d'autres personnes<\/li><li>Pr\u00e9parer de la nourriture pour des amis dans le besoin<\/li><li>Acheter des produits alimentaires pour les personnes confin\u00e9es \u00e0 la maison ou handicap\u00e9es<\/li><li>Passer des appels hebdomadaires pour prendre des nouvelles des amis et des parents<\/li><li>Envoyez des courriels, des SMS ou m\u00eame des lettres d'encouragement \u00e9crites \u00e0 la main.<\/li><li>Utiliser l'art et la musique pour inciter les autres \u00e0 garder espoir et \u00e0 rester positifs.<\/li><li>Lancer des chats de groupe pour parler de la vie quotidienne et s'encourager mutuellement <\/li><li>Partager des photos ou des vid\u00e9os souvenirs pour rester en contact avec la famille et les amis<\/li><\/ul>\n\n\n\n<p>Les gens peuvent partager des actes de gentillesse sur les m\u00e9dias sociaux (photo ou courte vid\u00e9o), faire un don \u00e0 la r\u00e9ponse COVID-19 d'ADRA, et d\u00e9fier d'autres amis de faire de m\u00eame en taguant leurs noms et en utilisant le hashtag de la campagne #GoodGoesViral.<\/p>\n\n\n\n<p><strong>\u00c9COUTE<\/strong> le site promotionnel #GoodGoesViral \u00e0   <a href=\"https:\/\/youtu.be\/0FyAJBfMQqk\">https:\/\/youtu.be\/0FyAJBfMQqk<\/a>.  <\/p>\n\n\n\n<p><strong>POUR LES DEMANDES DE RENSEIGNEMENTS DES M\u00c9DIAS<\/strong>, email <a href=\"mailto:press@adra.org\">press@adra.org<\/a>. <\/p>\n\n\n\n<p><strong>A PROPOS DE L'ADRA<\/strong><\/p>\n\n\n\n<p>L'Agence adventiste\nL'Agence adventiste de d\u00e9veloppement et de secours est le bras humanitaire international de l'\u00c9glise adventiste du septi\u00e8me jour.\nadventiste du septi\u00e8me jour. Son travail permet de renforcer les communaut\u00e9s et de changer des vies dans le monde entier en fournissant un d\u00e9veloppement communautaire durable et des secours en cas de catastrophe dans 118 pays.\nd\u00e9veloppement communautaire durable et des secours en cas de catastrophe dans 118 pays.\npays. <strong>Les dons pour contribuer \u00e0 la r\u00e9ponse \u00e0 la catastrophe du COVID-19 sont demand\u00e9s d'urgence \u00e0 l'adresse suivante\nCOVID-19 sont n\u00e9cessaires de toute urgence \u00e0 l'adresse suivante<\/strong>&nbsp;<a href=\"https:\/\/donations.adra.org\/covidresponse\" target=\"_blank\" rel=\"noreferrer noopener\">ADRA.org\/covidresponse<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Agence adventiste de d\u00e9veloppement et de secours (ADRA) lance la campagne Good Goes Viral (#GoodGoesViral), un mouvement visant \u00e0 inciter le monde \u00e0 s'engager dans des actes de bont\u00e9 \u00e0 partir du week-end de P\u00e2ques, \u00e0 prier pour les personnes touch\u00e9es par la crise du COVID-19 et \u00e0 soutenir la r\u00e9ponse mondiale de l'ADRA \u00e0 la pand\u00e9mie.<\/p>","protected":false},"author":1,"featured_media":18183,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","footnotes":""},"categories":[284],"tags":[774,8,709,690],"class_list":["post-18093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-health","tag-covid-19","tag-emergency-response","tag-mental-health-psychosocial-support-mhpss","tag-protection"],"acf":[],"_links":{"self":[{"href":"https:\/\/adra.org\/fr\/wp-json\/wp\/v2\/posts\/18093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adra.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adra.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adra.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adra.org\/fr\/wp-json\/wp\/v2\/comments?post=18093"}],"version-history":[{"count":21,"href":"https:\/\/adra.org\/fr\/wp-json\/wp\/v2\/posts\/18093\/revisions"}],"predecessor-version":[{"id":46450,"href":"https:\/\/adra.org\/fr\/wp-json\/wp\/v2\/posts\/18093\/revisions\/46450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adra.org\/fr\/wp-json\/wp\/v2\/media\/18183"}],"wp:attachment":[{"href":"https:\/\/adra.org\/fr\/wp-json\/wp\/v2\/media?parent=18093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adra.org\/fr\/wp-json\/wp\/v2\/categories?post=18093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adra.org\/fr\/wp-json\/wp\/v2\/tags?post=18093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}