{"id":1126,"date":"2011-03-22T17:53:35","date_gmt":"2011-03-22T17:53:35","guid":{"rendered":"http:\/\/sparkexperience.com\/projects\/adra\/?p=1126"},"modified":"2026-04-16T07:56:42","modified_gmt":"2026-04-16T07:56:42","slug":"flooding-in-namibia","status":"publish","type":"post","link":"https:\/\/adra.org\/es\/flooding-in-namibia","title":{"rendered":"Inundaciones en Namibia"},"content":{"rendered":"<h2>Namibia se prepara para las peores inundaciones de su historia: ADRA responde<\/h2>\n<p>SILVER SPRING, Maryland - Una peligrosa combinaci\u00f3n de fuertes lluvias y desbordamientos de los r\u00edos Kavango y Zambeze amenazan con obligar a decenas de miles de personas en Namibia a abandonar sus hogares. La Agencia Adventista de Desarrollo y Recursos Asistenciales (ADRA) est\u00e1 respondiendo, proporcionando suministros de emergencia a las personas que est\u00e1n en peligro de enfrentarse potencialmente a algunas de las peores inundaciones de la historia de Namibia.<\/p>\n<p>La intervenci\u00f3n de ADRA proporcionar\u00e1 agua potable a 10.000 personas del distrito de Kabeko, en la regi\u00f3n de Caprivi, mediante la distribuci\u00f3n de pastillas potabilizadoras. Las fuentes de agua se han contaminado por el desbordamiento de aguas fluviales impuras, lo que pone a miles de personas en peligro de contraer enfermedades transmitidas por el agua. Cada tableta purificadora tiene capacidad para purificar entre 20 y 25 litros de agua y proporcionar\u00e1 a los beneficiarios tres meses de agua limpia. Adem\u00e1s, ADRA est\u00e1 distribuyendo suministros b\u00e1sicos de emergencia, como mosquiteras y mantas. Se dar\u00e1 prioridad a las familias con ni\u00f1os peque\u00f1os o enfermos cr\u00f3nicos como medida de precauci\u00f3n para reducir el riesgo de exposici\u00f3n a la malaria.<\/p>\n<p>La regi\u00f3n de Caprivi est\u00e1 considerada la m\u00e1s h\u00fameda de Namibia y est\u00e1 muy acostumbrada a las lluvias torrenciales y las inundaciones estacionales, ya que la rodean varios r\u00edos y vastas marismas. Sin embargo, las lluvias inusualmente intensas de esta temporada y el gran caudal de agua de los r\u00edos han hecho que el r\u00edo Zambeze alcance vol\u00famenes r\u00e9cord y ya ha causado da\u00f1os en granjas, cultivos, ganado e infraestructuras.<\/p>\n<p>Los funcionarios del gobierno local ya han empezado a evacuar a los residentes a campos de asentamiento situados en zonas propensas a las inundaciones, entre ellos hay ni\u00f1os evacuados de internados. Seg\u00fan el Jefe de la Direcci\u00f3n de Emergencias, hay planes para evacuar a m\u00e1s de 50.000 personas en las pr\u00f3ximas semanas.<\/p>\n<p>ADRA, en colaboraci\u00f3n con la oficina del Consejero del Distrito de Kabeko y la Unidad Regional de Gesti\u00f3n de Emergencias, distribuir\u00e1 los suministros de socorro a lo largo de dos semanas. De los 10.000 beneficiarios, 6.000 est\u00e1n expuestos a agua potable contaminada, 4.000 son desplazados y 2.000 son ni\u00f1os menores de cinco a\u00f1os.<\/p>\n<p>ADRA Internacional, ADRA Sud\u00e1frica y la oficina de ADRA \u00c1frica Austral-Oc\u00e9ano \u00cdndico han financiado la intervenci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>Una peligrosa combinaci\u00f3n de fuertes lluvias y desbordamientos de los r\u00edos Kavango y Zambeze amenaza a decenas de miles de personas en Namibia con abandonar sus hogares.<\/p>","protected":false},"author":1,"featured_media":27874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","footnotes":""},"categories":[785,590,952,614,11],"tags":[748,1175,6,24,8,36,1069,1085],"class_list":["post-1126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa","category-emergency","category-namibia","category-news","category-press-release","tag-adra-responds","tag-clean-water","tag-disaster-relief","tag-disaster-response","tag-emergency-response","tag-flood-flooding-floods","tag-humanitarian-aid","tag-internally-displaced-persons-idps"],"acf":[],"_links":{"self":[{"href":"https:\/\/adra.org\/es\/wp-json\/wp\/v2\/posts\/1126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adra.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adra.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adra.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adra.org\/es\/wp-json\/wp\/v2\/comments?post=1126"}],"version-history":[{"count":4,"href":"https:\/\/adra.org\/es\/wp-json\/wp\/v2\/posts\/1126\/revisions"}],"predecessor-version":[{"id":48547,"href":"https:\/\/adra.org\/es\/wp-json\/wp\/v2\/posts\/1126\/revisions\/48547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adra.org\/es\/wp-json\/wp\/v2\/media\/27874"}],"wp:attachment":[{"href":"https:\/\/adra.org\/es\/wp-json\/wp\/v2\/media?parent=1126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adra.org\/es\/wp-json\/wp\/v2\/categories?post=1126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adra.org\/es\/wp-json\/wp\/v2\/tags?post=1126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}