{"id":1167,"date":"2012-05-10T19:11:28","date_gmt":"2012-05-10T19:11:28","guid":{"rendered":"http:\/\/sparkexperience.com\/projects\/adra\/?p=1167"},"modified":"2026-04-15T20:40:52","modified_gmt":"2026-04-15T20:40:52","slug":"transitioning-to-a-new-life","status":"publish","type":"post","link":"https:\/\/adra.org\/de\/transitioning-to-a-new-life","title":{"rendered":"Der \u00dcbergang zu einem neuen Leben"},"content":{"rendered":"<h2>Uganda: ADRA reagiert, um das Leben der kongolesischen Fl\u00fcchtlinge zu verbessern<\/h2>\n<p>SILVER SPRING, Md. - Nach den hitzigen Pr\u00e4sidentschaftswahlen im November 2011 in der Demokratischen Republik Kongo (DRK) halten die K\u00e4mpfe zwischen Regierungstruppen und bewaffneten Milizen an, was Tausende Kongolesen zur Flucht in das Nachbarland Uganda veranlasst hat. Das Adventistische Entwicklungs- und Hilfswerk (ADRA) unterst\u00fctzt Hunderte von Fl\u00fcchtlingsfamilien, die sich nun auf ein neues Leben in einem fremden Land einstellen m\u00fcssen.<\/p>\n<p>\u00dcber das \u00f6rtliche ADRA-B\u00fcro in Uganda wird die Agentur eine Ma\u00dfnahme durchf\u00fchren, die sich an 300 Fl\u00fcchtlingsfamilien richtet, die im westlichen Kisoro-Distrikt Ugandas im Nyakabande-Fl\u00fcchtlingszentrum leben. Vorrangig werden Minderj\u00e4hrige, unbegleitete Kinder und stillende\/erwartende M\u00fctter unterst\u00fctzt, die in Notsituationen Gefahr laufen, ausgegrenzt zu werden. Im Rahmen der Ma\u00dfnahme werden lebensnotwendige Hilfsg\u00fcter wie Decken, Wasserbeh\u00e4lter, Koch- und Essgeschirr sowie Moskitonetze zum Schutz vor Malaria verteilt.<\/p>\n<p>Das B\u00fcro des Premierministers von Uganda hat ADRA um Hilfe gebeten, um die Lebensbedingungen der kongolesischen Fl\u00fcchtlinge im Land zu verbessern. Im Rahmen der Hilfe arbeitet ADRA mit dem Hohen Fl\u00fcchtlingskommissar der Vereinten Nationen, dem Roten Kreuz Ugandas und den Mitarbeitern des Nyakabande-Fl\u00fcchtlingslagers zusammen, um eine Priorit\u00e4tenliste der Haushalte f\u00fcr die Verteilung zu erstellen und sicherzustellen, dass die entsprechenden Haushalte die NFI-Kits erhalten.<\/p>\n<p>ADRA ist seit 1986 in Uganda pr\u00e4sent und hat im ganzen Land eine Reihe von Hilfs- und Nothilfema\u00dfnahmen eingeleitet und durchgef\u00fchrt.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nach den hitzigen Pr\u00e4sidentschaftswahlen im November 2011 in der Demokratischen Republik Kongo (DRK) kam es zu anhaltenden K\u00e4mpfen zwischen Regierungstruppen und bewaffneten Milizen, die Tausende Kongolesen zur Flucht in das Nachbarland Uganda veranlassten.<\/p>","protected":false},"author":1,"featured_media":1315,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","footnotes":""},"categories":[785,807,11,825],"tags":[1079,8,1023,690,355],"class_list":["post-1167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-africa","category-dr-congo","category-press-release","category-uganda","tag-crisis","tag-emergency-response","tag-non-food-items-nfis","tag-protection","tag-refugees"],"acf":[],"_links":{"self":[{"href":"https:\/\/adra.org\/de\/wp-json\/wp\/v2\/posts\/1167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adra.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adra.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adra.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adra.org\/de\/wp-json\/wp\/v2\/comments?post=1167"}],"version-history":[{"count":4,"href":"https:\/\/adra.org\/de\/wp-json\/wp\/v2\/posts\/1167\/revisions"}],"predecessor-version":[{"id":48420,"href":"https:\/\/adra.org\/de\/wp-json\/wp\/v2\/posts\/1167\/revisions\/48420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adra.org\/de\/wp-json\/wp\/v2\/media\/1315"}],"wp:attachment":[{"href":"https:\/\/adra.org\/de\/wp-json\/wp\/v2\/media?parent=1167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adra.org\/de\/wp-json\/wp\/v2\/categories?post=1167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adra.org\/de\/wp-json\/wp\/v2\/tags?post=1167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}